{"id":478,"date":"2020-01-28T11:28:08","date_gmt":"2020-01-28T10:28:08","guid":{"rendered":"http:\/\/www.argia.eus\/blogak\/etxepare-rap\/?p=478"},"modified":"2020-01-28T11:28:08","modified_gmt":"2020-01-28T10:28:08","slug":"joan-tartas-hontsa-hiltzeko-bidia","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/","title":{"rendered":"Joan Tartas. Hontsa hiltzeko bidia."},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"100%\" height=\"166\" scrolling=\"no\" frameborder=\"no\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/726247408&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":100,"featured_media":479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/\" \/>\n<meta property=\"og:site_name\" content=\"Etxepare rap\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-28T10:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Imanol Epelde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imanol Epelde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/\"},\"author\":{\"name\":\"Imanol Epelde\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/#\\\/schema\\\/person\\\/3306874f94860fa819e574c7054d2481\"},\"headline\":\"Joan Tartas. Hontsa hiltzeko bidia.\",\"datePublished\":\"2020-01-28T10:28:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/\"},\"wordCount\":5,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/wp-content\\\/uploads\\\/sites\\\/98\\\/2020\\\/01\\\/Tartas-scaled.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/\",\"name\":\"Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/wp-content\\\/uploads\\\/sites\\\/98\\\/2020\\\/01\\\/Tartas-scaled.jpg\",\"datePublished\":\"2020-01-28T10:28:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/#\\\/schema\\\/person\\\/3306874f94860fa819e574c7054d2481\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/wp-content\\\/uploads\\\/sites\\\/98\\\/2020\\\/01\\\/Tartas-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/wp-content\\\/uploads\\\/sites\\\/98\\\/2020\\\/01\\\/Tartas-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/2020\\\/01\\\/28\\\/joan-tartas-hontsa-hiltzeko-bidia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joan Tartas. Hontsa hiltzeko bidia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/\",\"name\":\"Etxepare rap\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/#\\\/schema\\\/person\\\/3306874f94860fa819e574c7054d2481\",\"name\":\"Imanol Epelde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"caption\":\"Imanol Epelde\"},\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/etxepare-rap\\\/author\\\/etxepare-rap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/","og_locale":"en_US","og_type":"article","og_title":"Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap","og_url":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/","og_site_name":"Etxepare rap","article_published_time":"2020-01-28T10:28:08+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg","type":"image\/jpeg"}],"author":"Imanol Epelde","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Imanol Epelde"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/"},"author":{"name":"Imanol Epelde","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/#\/schema\/person\/3306874f94860fa819e574c7054d2481"},"headline":"Joan Tartas. Hontsa hiltzeko bidia.","datePublished":"2020-01-28T10:28:08+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/"},"wordCount":5,"commentCount":0,"image":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg","articleSection":["Blog"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/","url":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/","name":"Joan Tartas. Hontsa hiltzeko bidia. - Etxepare rap","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#primaryimage"},"image":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg","datePublished":"2020-01-28T10:28:08+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/#\/schema\/person\/3306874f94860fa819e574c7054d2481"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#primaryimage","url":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg","contentUrl":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-content\/uploads\/sites\/98\/2020\/01\/Tartas-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/2020\/01\/28\/joan-tartas-hontsa-hiltzeko-bidia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/etxepare-rap\/"},{"@type":"ListItem","position":2,"name":"Joan Tartas. Hontsa hiltzeko bidia."}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/#website","url":"https:\/\/blogak.argia.eus\/etxepare-rap\/","name":"Etxepare rap","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/etxepare-rap\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/etxepare-rap\/#\/schema\/person\/3306874f94860fa819e574c7054d2481","name":"Imanol Epelde","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","caption":"Imanol Epelde"},"url":"https:\/\/blogak.argia.eus\/etxepare-rap\/author\/etxepare-rap\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/posts\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/media\/479"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/etxepare-rap\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}