{"id":21,"count":6,"description":"","link":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/","name":"Filmak","slug":"filmak","taxonomy":"category","parent":11,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filmak Archives - 27 zapata<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filmak Archives - 27 zapata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/\" \/>\n<meta property=\"og:site_name\" content=\"27 zapata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/category\\\/literatura\\\/filmak\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/category\\\/literatura\\\/filmak\\\/\",\"name\":\"Filmak Archives - 27 zapata\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/category\\\/literatura\\\/filmak\\\/#breadcrumb\"},\"inLanguage\":\"eu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/category\\\/literatura\\\/filmak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Literatura\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/category\\\/literatura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filmak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\",\"name\":\"27 zapata\",\"description\":\"Autokritika umoretsua egunEROkotasunari\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filmak Archives - 27 zapata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/","og_locale":"en_US","og_type":"article","og_title":"Filmak Archives - 27 zapata","og_url":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/","og_site_name":"27 zapata","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/","name":"Filmak Archives - 27 zapata","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/#breadcrumb"},"inLanguage":"eu"},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/filmak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/"},{"@type":"ListItem","position":2,"name":"Literatura","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/category\/literatura\/"},{"@type":"ListItem","position":3,"name":"Filmak"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/","name":"27 zapata","description":"Autokritika umoretsua egunEROkotasunari","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/imanol-epelde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories\/11"}],"wp:post_type":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}