{"id":119,"date":"2008-05-06T17:44:55","date_gmt":"2008-05-06T17:44:55","guid":{"rendered":"http:\/\/www.27zapata.com\/?p=119"},"modified":"2008-05-06T17:44:55","modified_gmt":"2008-05-06T17:44:55","slug":"denbora-galduaren-bila","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/","title":{"rendered":"Denbora galduaren bila"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" height=\"500\" src=\"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif\" width=\"375\" \/><br \/>\u2026el olor y el sabor perduran mucho m\u00e1s, y recuerdan, y aguardan, y esperan, sobre las ruinas de todo, y soportan sin doblegarse en su impalpable gotita el edificio enorme del recuerdo.<br \/>\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 Marcel Proust<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2026el olor y el sabor perduran mucho m\u00e1s, y recuerdan, y aguardan, y esperan, sobre las ruinas de todo, y soportan sin doblegarse en su impalpable gotita el edificio enorme del recuerdo.\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-119","post","type-post","status-publish","format-standard","hentry","category-filmak"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Denbora galduaren bila<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Denbora galduaren bila\" \/>\n<meta property=\"og:description\" content=\"\u2026el olor y el sabor perduran mucho m\u00e1s, y recuerdan, y aguardan, y esperan, sobre las ruinas de todo, y soportan sin doblegarse en su impalpable gotita el edificio enorme del recuerdo.\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/\" \/>\n<meta property=\"og:site_name\" content=\"27 zapata\" \/>\n<meta property=\"article:published_time\" content=\"2008-05-06T17:44:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif\" \/>\n<meta name=\"author\" content=\"Imanol Epelde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imanol Epelde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/\"},\"author\":{\"name\":\"Imanol Epelde\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"headline\":\"Denbora galduaren bila\",\"datePublished\":\"2008-05-06T17:44:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/\"},\"wordCount\":81,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2008\\\/05\\\/2470504621_3beed17499.gif\",\"articleSection\":[\"Filmak\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/\",\"name\":\"Denbora galduaren bila\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2008\\\/05\\\/2470504621_3beed17499.gif\",\"datePublished\":\"2008-05-06T17:44:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2008\\\/05\\\/2470504621_3beed17499.gif\",\"contentUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2008\\\/05\\\/2470504621_3beed17499.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2008\\\/05\\\/06\\\/denbora-galduaren-bila\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Denbora galduaren bila\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\",\"name\":\"27 zapata\",\"description\":\"Autokritika umoretsua egunEROkotasunari\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\",\"name\":\"Imanol Epelde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"caption\":\"Imanol Epelde\"},\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/author\\\/imanol-epelde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Denbora galduaren bila","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/","og_locale":"en_US","og_type":"article","og_title":"Denbora galduaren bila","og_description":"\u2026el olor y el sabor perduran mucho m\u00e1s, y recuerdan, y aguardan, y esperan, sobre las ruinas de todo, y soportan sin doblegarse en su impalpable gotita el edificio enorme del recuerdo.\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 [&hellip;]","og_url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/","og_site_name":"27 zapata","article_published_time":"2008-05-06T17:44:55+00:00","og_image":[{"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif","type":"","width":"","height":""}],"author":"Imanol Epelde","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Imanol Epelde"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/"},"author":{"name":"Imanol Epelde","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"headline":"Denbora galduaren bila","datePublished":"2008-05-06T17:44:55+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/"},"wordCount":81,"commentCount":0,"image":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif","articleSection":["Filmak"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/","name":"Denbora galduaren bila","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#primaryimage"},"image":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif","datePublished":"2008-05-06T17:44:55+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#primaryimage","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif","contentUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2008\/05\/2470504621_3beed17499.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2008\/05\/06\/denbora-galduaren-bila\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/"},{"@type":"ListItem","position":2,"name":"Denbora galduaren bila"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/","name":"27 zapata","description":"Autokritika umoretsua egunEROkotasunari","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/imanol-epelde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398","name":"Imanol Epelde","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","caption":"Imanol Epelde"},"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/author\/imanol-epelde\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}