{"id":2508,"date":"2007-09-16T16:52:05","date_gmt":"2007-09-16T16:52:05","guid":{"rendered":"http:\/\/www.27zapata.com\/?p=10"},"modified":"2007-09-16T16:52:05","modified_gmt":"2007-09-16T16:52:05","slug":"mila-irudik-ere-ez","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/","title":{"rendered":"Mila irudik ere ez"},"content":{"rendered":"<p>Izan nintzen zoriontsu, egin ninduzuelako. Gau bat izan zen, sorginek egindako txupitotan bustia, eroa, suzkoa, lizuna. Akelarre modernoa. Gure bihotzetan. Mila uzker libre eta eder egin ninduzuen alproja guztioi. Mila esker bizitzari, horrelako uneak erregalatzeagatik, ezustean, sorpresan. <br \/>Atzo ez nuen kamerarik atera. Baina mila irudik ere ez zuten atzokoa adieraziko.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Izan nintzen zoriontsu, egin ninduzuelako. Gau bat izan zen, sorginek egindako txupitotan bustia, eroa, suzkoa, lizuna. Akelarre modernoa. Gure bihotzetan. Mila uzker libre eta eder egin ninduzuen alproja guztioi. Mila esker bizitzari, horrelako uneak erregalatzeagatik, ezustean, sorpresan. Atzo ez nuen [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-2508","post","type-post","status-publish","format-standard","hentry","category-27zapata"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mila irudik ere ez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mila irudik ere ez\" \/>\n<meta property=\"og:description\" content=\"Izan nintzen zoriontsu, egin ninduzuelako. Gau bat izan zen, sorginek egindako txupitotan bustia, eroa, suzkoa, lizuna. Akelarre modernoa. Gure bihotzetan. Mila uzker libre eta eder egin ninduzuen alproja guztioi. Mila esker bizitzari, horrelako uneak erregalatzeagatik, ezustean, sorpresan. Atzo ez nuen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/\" \/>\n<meta property=\"og:site_name\" content=\"27 zapata\" \/>\n<meta property=\"article:published_time\" content=\"2007-09-16T16:52:05+00:00\" \/>\n<meta name=\"author\" content=\"Imanol Epelde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imanol Epelde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/\"},\"author\":{\"name\":\"Imanol Epelde\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"headline\":\"Mila irudik ere ez\",\"datePublished\":\"2007-09-16T16:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/\"},\"wordCount\":54,\"commentCount\":1,\"articleSection\":[\"27zapata\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/\",\"name\":\"Mila irudik ere ez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\"},\"datePublished\":\"2007-09-16T16:52:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2007\\\/09\\\/16\\\/mila-irudik-ere-ez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mila irudik ere ez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\",\"name\":\"27 zapata\",\"description\":\"Autokritika umoretsua egunEROkotasunari\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\",\"name\":\"Imanol Epelde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"caption\":\"Imanol Epelde\"},\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/author\\\/imanol-epelde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mila irudik ere ez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/","og_locale":"en_US","og_type":"article","og_title":"Mila irudik ere ez","og_description":"Izan nintzen zoriontsu, egin ninduzuelako. Gau bat izan zen, sorginek egindako txupitotan bustia, eroa, suzkoa, lizuna. Akelarre modernoa. Gure bihotzetan. Mila uzker libre eta eder egin ninduzuen alproja guztioi. Mila esker bizitzari, horrelako uneak erregalatzeagatik, ezustean, sorpresan. Atzo ez nuen [&hellip;]","og_url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/","og_site_name":"27 zapata","article_published_time":"2007-09-16T16:52:05+00:00","author":"Imanol Epelde","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Imanol Epelde"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/"},"author":{"name":"Imanol Epelde","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"headline":"Mila irudik ere ez","datePublished":"2007-09-16T16:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/"},"wordCount":54,"commentCount":1,"articleSection":["27zapata"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/","name":"Mila irudik ere ez","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website"},"datePublished":"2007-09-16T16:52:05+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2007\/09\/16\/mila-irudik-ere-ez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/"},{"@type":"ListItem","position":2,"name":"Mila irudik ere ez"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/","name":"27 zapata","description":"Autokritika umoretsua egunEROkotasunari","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/imanol-epelde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398","name":"Imanol Epelde","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","caption":"Imanol Epelde"},"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/author\/imanol-epelde\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/2508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/comments?post=2508"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/2508\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/media?parent=2508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories?post=2508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/tags?post=2508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}