{"id":566,"date":"2011-09-22T06:46:40","date_gmt":"2011-09-22T06:46:40","guid":{"rendered":"http:\/\/www.27zapata.com\/?p=566"},"modified":"2011-09-22T06:46:40","modified_gmt":"2011-09-22T06:46:40","slug":"balada-bat-hilkutxarako-jon","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/","title":{"rendered":"Balada bat hilkutxarako, Jon"},"content":{"rendered":"<p>Handia izan da sorpresa. Jon Mirande idazle kuttunak twitter bidez jarraituko nauela jakin dut gaur goizean eta ezin nire ezinegona eta alegrantzia azaldu gabe gelditu. Hilkutxan jarri omen diote wifia, eta nik blog honetan umiltasunez laudoriotan \u201c<a href=\"http:\/\/www.basquepoetry.net\/poemak\/0390.htm\" target=\"_blank\" rel=\"noopener\">Euskaldun zintzoen balada<\/a>\u201d izeneko letra kantu bihurtu dut, atrebentzia handiak hartuta, bistan da.<\/p>\n<p>Oh, Jon, kantua ez dago behar bezala amaituta, oraindik falta ditu aldaketa asko. Baina ezin tentazioari, gure jainko partikularrari, bizkarrik eman!<\/p>\n<div>\n<p><a style=\"font-family: arial, helvetica, sans-serif;font-size: 11px;font-weight: normal;padding-left: 41px;color: #2DA274;text-decoration: none;border-bottom: none\" href=\"http:\/\/www.podbean.com\">Podcast Powered By Podbean<\/a>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Handia izan da sorpresa. Jon Mirande idazle kuttunak twitter bidez jarraituko nauela jakin dut gaur goizean eta ezin nire ezinegona eta alegrantzia azaldu gabe gelditu. Hilkutxan jarri omen diote wifia, eta nik blog honetan umiltasunez laudoriotan \u201cEuskaldun zintzoen balada\u201d izeneko [&hellip;]<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-566","post","type-post","status-publish","format-standard","hentry","category-27zapata"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Balada bat hilkutxarako, Jon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balada bat hilkutxarako, Jon\" \/>\n<meta property=\"og:description\" content=\"Handia izan da sorpresa. Jon Mirande idazle kuttunak twitter bidez jarraituko nauela jakin dut gaur goizean eta ezin nire ezinegona eta alegrantzia azaldu gabe gelditu. Hilkutxan jarri omen diote wifia, eta nik blog honetan umiltasunez laudoriotan \u201cEuskaldun zintzoen balada\u201d izeneko [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/\" \/>\n<meta property=\"og:site_name\" content=\"27 zapata\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-22T06:46:40+00:00\" \/>\n<meta name=\"author\" content=\"Imanol Epelde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imanol Epelde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/\"},\"author\":{\"name\":\"Imanol Epelde\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"headline\":\"Balada bat hilkutxarako, Jon\",\"datePublished\":\"2011-09-22T06:46:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/\"},\"wordCount\":78,\"commentCount\":0,\"articleSection\":[\"27zapata\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/\",\"name\":\"Balada bat hilkutxarako, Jon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\"},\"datePublished\":\"2011-09-22T06:46:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2011\\\/09\\\/22\\\/balada-bat-hilkutxarako-jon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Balada bat hilkutxarako, Jon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\",\"name\":\"27 zapata\",\"description\":\"Autokritika umoretsua egunEROkotasunari\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\",\"name\":\"Imanol Epelde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"caption\":\"Imanol Epelde\"},\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/author\\\/imanol-epelde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Balada bat hilkutxarako, Jon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/","og_locale":"en_US","og_type":"article","og_title":"Balada bat hilkutxarako, Jon","og_description":"Handia izan da sorpresa. Jon Mirande idazle kuttunak twitter bidez jarraituko nauela jakin dut gaur goizean eta ezin nire ezinegona eta alegrantzia azaldu gabe gelditu. Hilkutxan jarri omen diote wifia, eta nik blog honetan umiltasunez laudoriotan \u201cEuskaldun zintzoen balada\u201d izeneko [&hellip;]","og_url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/","og_site_name":"27 zapata","article_published_time":"2011-09-22T06:46:40+00:00","author":"Imanol Epelde","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Imanol Epelde"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/"},"author":{"name":"Imanol Epelde","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"headline":"Balada bat hilkutxarako, Jon","datePublished":"2011-09-22T06:46:40+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/"},"wordCount":78,"commentCount":0,"articleSection":["27zapata"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/","name":"Balada bat hilkutxarako, Jon","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website"},"datePublished":"2011-09-22T06:46:40+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2011\/09\/22\/balada-bat-hilkutxarako-jon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/"},{"@type":"ListItem","position":2,"name":"Balada bat hilkutxarako, Jon"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/","name":"27 zapata","description":"Autokritika umoretsua egunEROkotasunari","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/imanol-epelde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398","name":"Imanol Epelde","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","caption":"Imanol Epelde"},"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/author\/imanol-epelde\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/comments?post=566"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/566\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/media?parent=566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories?post=566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/tags?post=566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}