{"id":818,"date":"2013-11-27T17:24:23","date_gmt":"2013-11-27T17:24:23","guid":{"rendered":"http:\/\/www.27zapata.com\/?p=818"},"modified":"2013-11-27T17:24:23","modified_gmt":"2013-11-27T17:24:23","slug":"ama","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/","title":{"rendered":"Ama"},"content":{"rendered":"<p style=\"text-align: center\"><a href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu.jpg\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-819 aligncenter\" alt=\"manoli_zaitugu\" src=\"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg\" width=\"442\" height=\"500\" \/><\/a><\/p>\n<p style=\"text-align: center\"><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0<\/p>\n","protected":false},"author":101,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[45],"class_list":["post-818","post","type-post","status-publish","format-standard","hentry","category-27zapata","tag-ama"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ama\" \/>\n<meta property=\"og:description\" content=\"\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/\" \/>\n<meta property=\"og:site_name\" content=\"27 zapata\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-27T17:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg\" \/>\n<meta name=\"author\" content=\"Imanol Epelde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Imanol Epelde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/\"},\"author\":{\"name\":\"Imanol Epelde\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"headline\":\"Ama\",\"datePublished\":\"2013-11-27T17:24:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/\"},\"wordCount\":1,\"commentCount\":26,\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2013\\\/11\\\/manoli_zaitugu-242x300.jpg\",\"keywords\":[\"ama\"],\"articleSection\":[\"27zapata\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/\",\"name\":\"Ama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2013\\\/11\\\/manoli_zaitugu-242x300.jpg\",\"datePublished\":\"2013-11-27T17:24:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2013\\\/11\\\/manoli_zaitugu-242x300.jpg\",\"contentUrl\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2013\\\/11\\\/manoli_zaitugu-242x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/2013\\\/11\\\/27\\\/ama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/\",\"name\":\"27 zapata\",\"description\":\"Autokritika umoretsua egunEROkotasunari\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/#\\\/schema\\\/person\\\/2208bcffc9f58c4a77ddfcd8c49b7398\",\"name\":\"Imanol Epelde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g\",\"caption\":\"Imanol Epelde\"},\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/imanol-epelde\\\/author\\\/imanol-epelde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/","og_locale":"en_US","og_type":"article","og_title":"Ama","og_description":"\u00a0","og_url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/","og_site_name":"27 zapata","article_published_time":"2013-11-27T17:24:23+00:00","og_image":[{"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg","type":"","width":"","height":""}],"author":"Imanol Epelde","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Imanol Epelde"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/"},"author":{"name":"Imanol Epelde","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"headline":"Ama","datePublished":"2013-11-27T17:24:23+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/"},"wordCount":1,"commentCount":26,"image":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg","keywords":["ama"],"articleSection":["27zapata"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/","name":"Ama","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#primaryimage"},"image":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#primaryimage"},"thumbnailUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg","datePublished":"2013-11-27T17:24:23+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#primaryimage","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg","contentUrl":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-content\/uploads\/sites\/99\/2013\/11\/manoli_zaitugu-242x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/2013\/11\/27\/ama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/imanol-epelde\/"},{"@type":"ListItem","position":2,"name":"Ama"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#website","url":"https:\/\/blogak.argia.eus\/imanol-epelde\/","name":"27 zapata","description":"Autokritika umoretsua egunEROkotasunari","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/imanol-epelde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/imanol-epelde\/#\/schema\/person\/2208bcffc9f58c4a77ddfcd8c49b7398","name":"Imanol Epelde","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb7708dedcd76b0b8f800e11ba55ccbedec146e9afe557f2ac2458008c70f5d5?s=96&d=mm&r=g","caption":"Imanol Epelde"},"url":"https:\/\/blogak.argia.eus\/imanol-epelde\/author\/imanol-epelde\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/comments?post=818"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/posts\/818\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/media?parent=818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/categories?post=818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/imanol-epelde\/wp-json\/wp\/v2\/tags?post=818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}