{"id":12797,"date":"2012-09-18T11:37:34","date_gmt":"2012-09-18T11:37:34","guid":{"rendered":"http:\/\/12797"},"modified":"2012-09-18T11:37:34","modified_gmt":"2012-09-18T11:37:34","slug":"converter-cada-falante-en-normalizador-a","status":"publish","type":"post","link":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/","title":{"rendered":"Converter cada falante en normalizador\/a"},"content":{"rendered":"<h4>Galiciaconfidencial apresenta a traduci\u00f3n ao galego do artigo publicado polo socioling\u00fcista basco Txerra Rodr\u00edguez na revista Argia sobre o proceso normalizador en Galicia.<\/h4>\n<div id=\"iconos_noticia\">A revista Argia,\u00a0 Luz em euskera,\u00a0 \u00e9 umha publica\u00e7om de informa\u00e7om geral com mais de noventa anos de vida. Actualmente publica-se tam\u00e9m online, com licen\u00e7a creative commmons, e contem umha canle multimedia\u00a0<a href=\"http:\/\/www.argia.com\/multimedia\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.argia.com\/multimedia\/<\/a>\u00a0com numerosos recursos sobre a lingua de Euskal Herria, onde proximamente poderemos olhar umha reportagem audiovisual de Txerra Rodr\u00edguez sobre os contidos deste artigo.<\/div>\n<div>\n<p>O autor do artigo, Txerra Rodr\u00edguez, \u00e9 socioling\u00fcista e trabalha como normalizador na cooperativa de servi\u00e7os ling\u00fc\u00edsticos\u00a0Hizkuntza teknikaria\u00a0en\u00a0<a href=\"http:\/\/es.linkedin.com\/company\/emun-koop.e.?trk=ppro_cprof\" target=\"_blank\" rel=\"noopener\">Emun Koop, num equipo com mais de cem trabalhadoras e trabalhadores.\u00a0<\/a>Txerra Rodr\u00edguez gestiona o blog\u00a0<a href=\"http:\/\/www.blogak.com\/garaigoikoa\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.blogak.com\/garaigoikoa\/<\/a>\u00a0e tem publicado diversos textos sobre euskera. No 2012 traduciu do galego para o euskera o livro Made in Galiza, de S\u00e9chu Sende, editado pola editora Txalaparta.<\/p>\n<p>*********************************************************************************************************<\/p>\n<p align=\"center\"><b>Converter cada falante em normalizador\/a<\/b><\/p>\n<p>Nom \u00e9 mui frecuente achar aqui, em Euskal Herria, as palavras justi\u00e7a social e normaliza\u00e7om ling\u00fc\u00edstica na mesma frase. Nom \u00e9 mui frecuente aqui escuitar a seguinte pergunta: Pode-se ser feminista e viver em castel\u00e1m? Por todo isso, decidim\u00a0 ir en julho a Galiza, a um curso de verao.<\/p>\n<p>O curso foi em Carvalho, na Corunha. O curso estava organizado pola CTNL (Coordinadora de Traballadores\/as de Normalizaci\u00f3n da Lingua, a associa\u00e7om de persoal t\u00e9cnico de normaliza\u00e7om galega) e pola universidade da Corunha e durou tr\u00eas dias. Para o curso, convidarom a falar em p\u00fablico a feministas, ecologistas, imigrantes, ativistas, militantes a favor dos direitos das lesbianas, mocidade e demais.<\/p>\n<p>Atuar a favor do galego \u00e9 justo, \u00e9 umha causa justa. E o galego tem que unir-se ao resto de causas justas. \u00c9ssa \u00e9 a conclusom fundamental\u00a0 \u00e1 que chegarom as persoas organizadoras do curso. Pero eu tam\u00e9m tirei outras conclusons, que penso que se podem aplicar no nosso pa\u00eds sem demasiada dificultade.<\/p>\n<p>Mais dumha ponhente e dalgum participante falou de autoconfianza, ou dizendo o mesmo com outras palavras: orgulho, empoderamento. At\u00e9 o de agora quem trabalhou a favor do galego trabalhou muito nas fun\u00e7ons de mais alto rango: universidade, m\u00e9dios de comunica\u00e7om, administra\u00e7om, justi\u00e7a. Em fun\u00e7ons de alto rango e muitas vezes exigindo \u00e1 administra\u00e7om.<\/p>\n<p>Mas parece que as cousas est\u00e1m a mudar, ainda que seja pouco a pouco. Nos \u00faltimos tempos aparecerom medios de comunica\u00e7om mediante participa\u00e7om popular (Sermos, Praza, Dioivo), escolas ou projectos de escola mediante participaci\u00f3n popular (Semente, a iniciativa Galiza co galego), novos modelos de interven\u00e7om normalizadora (Modelo Burela), etc\u00e9tera.<\/p>\n<p>Talvez chegou o momento de dar a ciaboga, como dixerom nas jornadas. Talvez chegou o momento de cambiar a estrat\u00e9gia. Isso nom significa de ningum jeito que se tenha que deixar a um lado o trabalho a favor das fun\u00e7ons de alto rango, nem significa que se tenha que deixar de exigir \u00e1 administra\u00e7om que cumpra o que deve cumprir. De ningum jeito. Mas, ao melhor, chegou o momento de abrir novos caminhos, novas linhas de trabalho.<\/p>\n<p><b>Mimar as persoas falante<\/b>s<\/p>\n<p>At\u00e9 o de agora nom se tratara com a profundidade que se dever\u00eda \u00e1s persoas falantes de galego, at\u00e9 o de agora nom se trabalharom\u00a0 como se deveriam as actitudes das persoas falantes, nom se trabalhou diretamente sobre a lealdade ling\u00fc\u00edstica. E talvez chegou o momento de cuidar os falantes e as falantes de galego, de arroupa-los, j\u00e1 que eles e elas som os verdadeiros motores da normaliza\u00e7om.<\/p>\n<p>H\u00e1 que dar mais import\u00e1ncia \u00e1s pr\u00e1ticas coti\u00e1s das persoas galegofalantes, h\u00e1 que dar-lhe folgos \u00e1 lealdade. \u00c9 imprescind\u00edvel ter falantes que estejam plenos de orgulho e confianza. Cada comunidade debe intentar dirigir-se a si mesma, debe intentar cuidar-se a si mesma. E para isso \u00e9 necess\u00e1rio contar com falantes que cream na propia comunidade.<\/p>\n<p>Tam\u00e9m \u00e9 convinte aprender doutros movimentos sociais -que defendem tam\u00e9m causas justas- as ferramentas que usam e intentar adaptar \u00e1 normaliza\u00e7om ling\u00fc\u00edstica: por exemplo, as estrat\u00e9gias de empoderamento que usa o feminismo, as t\u00e9cnicas para fundir preju\u00ed\u00e7os, as formas de luita e negocia\u00e7om que h\u00e1 que levar com a administra\u00e7om\u2026<\/p>\n<p>O objetivo: criar e proteger as persoas falantes que nos sirvam de modelo. Porque cada persoa que fala galego \u00e9 um agente normalizador, \u00e9 um sujeito do c\u00e1mbio (ou mantemento) ling\u00fc\u00edstico. As persoas falantes de galego devem interiorizar que elas tam\u00e9m som agentes normalizadores e adecuar polo tanto as suas atitudes ling\u00fc\u00edsticas. E, para isso, \u00e9 necess\u00e1rio mimar as persoas falantes.<\/p>\n<p>Tratarom-se ali outros muitos temas: falou-se de sostibilidade ling\u00fc\u00edstica, de transmisom familiar, da volta ao rural, de imperialismo ling\u00fc\u00edstico, de justi\u00e7a, de redes horizontais, de Internet,\u2026<\/p>\n<p>Salvando as dist\u00e1ncias, o ouvido e vivido nessas jornadas nom \u00e9 mui diferente do que podemos ouvir e viver em jornadas similares aqui. \u00c9 mais, em muitos casos onde diziam Galiza podia-se p\u00f3r Euskal Herria e a situa\u00e7om seria quase igual. Isso si, enriquece-se muito um recolhendo diferentes preocupa\u00e7ons e viv\u00e9ncias.<\/p>\n<p><b>Modelo Burela<\/b><\/p>\n<p>Burela \u00e9 umha vila da Marinha de Lugo, que tem uns 12.000 habitantes. Desde fai sete anos esta-se a realizar umha interven\u00e7om socioling\u00fc\u00edstica conhecida como Modelo Burela. Tenhem um plano ling\u00fc\u00edstico singular ali.<\/p>\n<p>\u00c9 um plano feito de abaixo arriba, protagonizado polo alunado e professorado do liceu e aceptado polo concelho por unanimidade. \u00c9 um plano participativo levado adiante pola gente nova, professorado e<br \/>\ncidadania de Burela. No tenhem persoal t\u00e9cnico de normaliza\u00e7om.<\/p>\n<p>At\u00e9 o momento, cada ano trabalharom sobre um tema: cemit\u00e9rio, notarias, com\u00e9rcio, igreja, sanidade, m\u00fasica. Dam-lhes umha especial aten\u00e7om aos novos falantes, assi como tam\u00e9m \u00e1s persoas imigrantes. Em R\u00e1dio Burela fazem um programa semanal chamado Projecto Neo. Em cada programa participa umha o v\u00e1rias persoas que aprenderom o galego como adultos. O Modelo Burela recebeu numerosos pr\u00e9mios na Galiza e em Espanha \u00e1 inova\u00e7om pedag\u00f3gica. Escrevendo\u00a0 \u201cModelo Burela\u201d na rede, podereis achar um document\u00e1rio de arredor dumha hora. Ademais proximamente na canle multim\u00e9dia de Argia achareis umha reportagem sobre este projecto.<\/p>\n<p><i>Txerra Rodr\u00edguez<\/i><\/p>\n<p><i>Revista Argia, setembro 2012.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Galiciaconfidencial apresenta a traduci\u00f3n ao galego do artigo publicado polo socioling\u00fcista basco Txerra Rodr\u00edguez na revista Argia sobre o proceso normalizador en Galicia. A revista Argia,\u00a0 Luz em euskera,\u00a0 \u00e9 umha publica\u00e7om de informa\u00e7om geral com mais de noventa anos de vida. Actualmente publica-se tam\u00e9m online, com licen\u00e7a creative commmons, e contem umha canle multimedia\u00a0http:\/\/www.argia.com\/multimedia\/\u00a0com [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[82,531,620,658,109,178,4,5,49],"class_list":["post-12797","post","type-post","status-publish","format-standard","hentry","category-sailkatu-gabea","tag-argia","tag-carballo","tag-ctnl","tag-galiciaconfidencial","tag-galizia","tag-hizkuntza","tag-sl","tag-soziolinguistika","tag-soziologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Converter cada falante en normalizador\/a - Garaigoikoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Converter cada falante en normalizador\/a - Garaigoikoa\" \/>\n<meta property=\"og:description\" content=\"Galiciaconfidencial apresenta a traduci\u00f3n ao galego do artigo publicado polo socioling\u00fcista basco Txerra Rodr\u00edguez na revista Argia sobre o proceso normalizador en Galicia. A revista Argia,\u00a0 Luz em euskera,\u00a0 \u00e9 umha publica\u00e7om de informa\u00e7om geral com mais de noventa anos de vida. Actualmente publica-se tam\u00e9m online, com licen\u00e7a creative commmons, e contem umha canle multimedia\u00a0http:\/\/www.argia.com\/multimedia\/\u00a0com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Garaigoikoa\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-18T11:37:34+00:00\" \/>\n<meta name=\"author\" content=\"Txerra Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@garaigoikoa\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Txerra Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/\"},\"author\":{\"name\":\"Txerra Rodriguez\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/#\\\/schema\\\/person\\\/460e679562b6c6b679cf78f49a422b25\"},\"headline\":\"Converter cada falante en normalizador\\\/a\",\"datePublished\":\"2012-09-18T11:37:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/\"},\"wordCount\":1057,\"commentCount\":0,\"keywords\":[\"argia\",\"carballo\",\"ctnl\",\"galiciaconfidencial\",\"galizia\",\"hizkuntza\",\"sl\",\"soziolinguistika\",\"soziologia\"],\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/\",\"name\":\"Converter cada falante en normalizador\\\/a - Garaigoikoa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/#website\"},\"datePublished\":\"2012-09-18T11:37:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/#\\\/schema\\\/person\\\/460e679562b6c6b679cf78f49a422b25\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/2012\\\/09\\\/18\\\/converter-cada-falante-en-normalizador-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Converter cada falante en normalizador\\\/a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/\",\"name\":\"Garaigoikoa\",\"description\":\"Hizkuntza soziologia (edo soziolinguistika)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/#\\\/schema\\\/person\\\/460e679562b6c6b679cf78f49a422b25\",\"name\":\"Txerra Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g\",\"caption\":\"Txerra Rodriguez\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/garaigoikoa\"],\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/txerra-rodriguez\\\/author\\\/txerra-rodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Converter cada falante en normalizador\/a - Garaigoikoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/","og_locale":"en_US","og_type":"article","og_title":"Converter cada falante en normalizador\/a - Garaigoikoa","og_description":"Galiciaconfidencial apresenta a traduci\u00f3n ao galego do artigo publicado polo socioling\u00fcista basco Txerra Rodr\u00edguez na revista Argia sobre o proceso normalizador en Galicia. A revista Argia,\u00a0 Luz em euskera,\u00a0 \u00e9 umha publica\u00e7om de informa\u00e7om geral com mais de noventa anos de vida. Actualmente publica-se tam\u00e9m online, com licen\u00e7a creative commmons, e contem umha canle multimedia\u00a0http:\/\/www.argia.com\/multimedia\/\u00a0com [&hellip;]","og_url":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/","og_site_name":"Garaigoikoa","article_published_time":"2012-09-18T11:37:34+00:00","author":"Txerra Rodriguez","twitter_card":"summary_large_image","twitter_creator":"@garaigoikoa","twitter_misc":{"Written by":"Txerra Rodriguez","Est. reading time":"5 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/#article","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/"},"author":{"name":"Txerra Rodriguez","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/#\/schema\/person\/460e679562b6c6b679cf78f49a422b25"},"headline":"Converter cada falante en normalizador\/a","datePublished":"2012-09-18T11:37:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/"},"wordCount":1057,"commentCount":0,"keywords":["argia","carballo","ctnl","galiciaconfidencial","galizia","hizkuntza","sl","soziolinguistika","soziologia"],"inLanguage":"eu","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/","url":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/","name":"Converter cada falante en normalizador\/a - Garaigoikoa","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/#website"},"datePublished":"2012-09-18T11:37:34+00:00","author":{"@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/#\/schema\/person\/460e679562b6c6b679cf78f49a422b25"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/2012\/09\/18\/converter-cada-falante-en-normalizador-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/"},{"@type":"ListItem","position":2,"name":"Converter cada falante en normalizador\/a"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/#website","url":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/","name":"Garaigoikoa","description":"Hizkuntza soziologia (edo soziolinguistika)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/#\/schema\/person\/460e679562b6c6b679cf78f49a422b25","name":"Txerra Rodriguez","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/84c33467efd80cea8ce40cf1e4a2e452b6ab9c51622e1a63fa9960d7fc6fa113?s=96&d=mm&r=g","caption":"Txerra Rodriguez"},"sameAs":["https:\/\/x.com\/garaigoikoa"],"url":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/author\/txerra-rodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/posts\/12797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/comments?post=12797"}],"version-history":[{"count":0,"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/posts\/12797\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/media?parent=12797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/categories?post=12797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogak.argia.eus\/txerra-rodriguez\/wp-json\/wp\/v2\/tags?post=12797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}