{"id":10,"count":30,"description":"","link":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/","name":"Gizartea","slug":"gizartea","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gizartea Archives - Gazteluko plazatik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gizartea Archives - Gazteluko plazatik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/\" \/>\n<meta property=\"og:site_name\" content=\"Gazteluko plazatik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/category\\\/gizartea\\\/\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/category\\\/gizartea\\\/\",\"name\":\"Gizartea Archives - Gazteluko plazatik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/category\\\/gizartea\\\/#breadcrumb\"},\"inLanguage\":\"eu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/category\\\/gizartea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gizartea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/#website\",\"url\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/\",\"name\":\"Gazteluko plazatik\",\"description\":\"Politika eta ekonomia bidegurutzea\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogak.argia.eus\\\/xabier-letona\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gizartea Archives - Gazteluko plazatik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/","og_locale":"en_US","og_type":"article","og_title":"Gizartea Archives - Gazteluko plazatik","og_url":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/","og_site_name":"Gazteluko plazatik","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/","url":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/","name":"Gizartea Archives - Gazteluko plazatik","isPartOf":{"@id":"https:\/\/blogak.argia.eus\/xabier-letona\/#website"},"breadcrumb":{"@id":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/#breadcrumb"},"inLanguage":"eu"},{"@type":"BreadcrumbList","@id":"https:\/\/blogak.argia.eus\/xabier-letona\/category\/gizartea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogak.argia.eus\/xabier-letona\/"},{"@type":"ListItem","position":2,"name":"Gizartea"}]},{"@type":"WebSite","@id":"https:\/\/blogak.argia.eus\/xabier-letona\/#website","url":"https:\/\/blogak.argia.eus\/xabier-letona\/","name":"Gazteluko plazatik","description":"Politika eta ekonomia bidegurutzea","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogak.argia.eus\/xabier-letona\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"}]}},"_links":{"self":[{"href":"https:\/\/blogak.argia.eus\/xabier-letona\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogak.argia.eus\/xabier-letona\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogak.argia.eus\/xabier-letona\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogak.argia.eus\/xabier-letona\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}